{"id":76,"count":2,"description":"","link":"https:\/\/blog.gdsys.de\/en\/tag\/employees\/","name":"employees","slug":"employees","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>employees Archives - G&amp;D Corporate Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.gdsys.de\/en\/tag\/employees\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"employees Archives - G&amp;D Corporate Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.gdsys.de\/en\/tag\/employees\/\" \/>\n<meta property=\"og:site_name\" content=\"G&amp;D Corporate Blog\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blog.gdsys.de\/en\/#website\",\"url\":\"https:\/\/blog.gdsys.de\/en\/\",\"name\":\"G&amp;D Corporate Blog\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blog.gdsys.de\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/blog.gdsys.de\/en\/tag\/employees\/#webpage\",\"url\":\"https:\/\/blog.gdsys.de\/en\/tag\/employees\/\",\"name\":\"employees Archives - G&amp;D Corporate Blog\",\"isPartOf\":{\"@id\":\"https:\/\/blog.gdsys.de\/en\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/blog.gdsys.de\/en\/tag\/employees\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/blog.gdsys.de\/en\/tag\/employees\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blog.gdsys.de\/en\/tag\/employees\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"employees\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"employees Archives - G&amp;D Corporate Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.gdsys.de\/en\/tag\/employees\/","og_locale":"en_US","og_type":"article","og_title":"employees Archives - G&amp;D Corporate Blog","og_url":"https:\/\/blog.gdsys.de\/en\/tag\/employees\/","og_site_name":"G&amp;D Corporate Blog","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/blog.gdsys.de\/en\/#website","url":"https:\/\/blog.gdsys.de\/en\/","name":"G&amp;D Corporate Blog","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.gdsys.de\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"CollectionPage","@id":"https:\/\/blog.gdsys.de\/en\/tag\/employees\/#webpage","url":"https:\/\/blog.gdsys.de\/en\/tag\/employees\/","name":"employees Archives - G&amp;D Corporate Blog","isPartOf":{"@id":"https:\/\/blog.gdsys.de\/en\/#website"},"breadcrumb":{"@id":"https:\/\/blog.gdsys.de\/en\/tag\/employees\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.gdsys.de\/en\/tag\/employees\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/blog.gdsys.de\/en\/tag\/employees\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"employees"}]}]}},"_links":{"self":[{"href":"https:\/\/blog.gdsys.de\/en\/wp-json\/wp\/v2\/tags\/76"}],"collection":[{"href":"https:\/\/blog.gdsys.de\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blog.gdsys.de\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blog.gdsys.de\/en\/wp-json\/wp\/v2\/posts?tags=76"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}