{"id":153,"count":3,"description":"","link":"https:\/\/blog.gdsys.de\/en\/tag\/mouse\/","name":"mouse","slug":"mouse","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>mouse Archives - G&amp;D Corporate Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.gdsys.de\/en\/tag\/mouse\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"mouse Archives - G&amp;D Corporate Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.gdsys.de\/en\/tag\/mouse\/\" \/>\n<meta property=\"og:site_name\" content=\"G&amp;D Corporate Blog\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blog.gdsys.de\/en\/#website\",\"url\":\"https:\/\/blog.gdsys.de\/en\/\",\"name\":\"G&amp;D Corporate Blog\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blog.gdsys.de\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/blog.gdsys.de\/en\/tag\/mouse\/#webpage\",\"url\":\"https:\/\/blog.gdsys.de\/en\/tag\/mouse\/\",\"name\":\"mouse Archives - G&amp;D Corporate Blog\",\"isPartOf\":{\"@id\":\"https:\/\/blog.gdsys.de\/en\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/blog.gdsys.de\/en\/tag\/mouse\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/blog.gdsys.de\/en\/tag\/mouse\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blog.gdsys.de\/en\/tag\/mouse\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"mouse\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"mouse Archives - G&amp;D Corporate Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.gdsys.de\/en\/tag\/mouse\/","og_locale":"en_US","og_type":"article","og_title":"mouse Archives - G&amp;D Corporate Blog","og_url":"https:\/\/blog.gdsys.de\/en\/tag\/mouse\/","og_site_name":"G&amp;D Corporate Blog","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/blog.gdsys.de\/en\/#website","url":"https:\/\/blog.gdsys.de\/en\/","name":"G&amp;D Corporate Blog","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.gdsys.de\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"CollectionPage","@id":"https:\/\/blog.gdsys.de\/en\/tag\/mouse\/#webpage","url":"https:\/\/blog.gdsys.de\/en\/tag\/mouse\/","name":"mouse Archives - G&amp;D Corporate Blog","isPartOf":{"@id":"https:\/\/blog.gdsys.de\/en\/#website"},"breadcrumb":{"@id":"https:\/\/blog.gdsys.de\/en\/tag\/mouse\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.gdsys.de\/en\/tag\/mouse\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/blog.gdsys.de\/en\/tag\/mouse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"mouse"}]}]}},"_links":{"self":[{"href":"https:\/\/blog.gdsys.de\/en\/wp-json\/wp\/v2\/tags\/153"}],"collection":[{"href":"https:\/\/blog.gdsys.de\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blog.gdsys.de\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blog.gdsys.de\/en\/wp-json\/wp\/v2\/posts?tags=153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}